{"id":9233,"count":3,"description":"","link":"https:\/\/www.wormholeriders.com\/blog\/category\/celebs\/jessica-mcleod\/","name":"Jessica McLeod","slug":"jessica-mcleod","taxonomy":"category","parent":10,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Jessica McLeod Archives - WormholeRiders News Agency<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.wormholeriders.com\/blog\/category\/celebs\/jessica-mcleod\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jessica McLeod Archives - WormholeRiders News Agency\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.wormholeriders.com\/blog\/category\/celebs\/jessica-mcleod\/\" \/>\n<meta property=\"og:site_name\" content=\"WormholeRiders News Agency\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.wormholeriders.com\\\/blog\\\/category\\\/celebs\\\/jessica-mcleod\\\/\",\"url\":\"https:\\\/\\\/www.wormholeriders.com\\\/blog\\\/category\\\/celebs\\\/jessica-mcleod\\\/\",\"name\":\"Jessica McLeod Archives - WormholeRiders News Agency\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.wormholeriders.com\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.wormholeriders.com\\\/blog\\\/category\\\/celebs\\\/jessica-mcleod\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.wormholeriders.com\\\/blog\\\/category\\\/celebs\\\/jessica-mcleod\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.wormholeriders.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Celebs\",\"item\":\"https:\\\/\\\/www.wormholeriders.com\\\/blog\\\/category\\\/celebs\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Jessica McLeod\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.wormholeriders.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.wormholeriders.com\\\/blog\\\/\",\"name\":\"WormholeRiders News Agency\",\"description\":\"Please Keep Your Arms and Legs Inside the Wormhole at All Times!\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.wormholeriders.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.wormholeriders.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.wormholeriders.com\\\/blog\\\/#organization\",\"name\":\"WormholeRiders News Agency\",\"url\":\"https:\\\/\\\/www.wormholeriders.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.wormholeriders.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.wormholeriders.com\\\/blog\\\/wp-content\\\/uploads\\\/WormholeRiders-New-Logo-150TS-Dark.png\",\"contentUrl\":\"https:\\\/\\\/www.wormholeriders.com\\\/blog\\\/wp-content\\\/uploads\\\/WormholeRiders-New-Logo-150TS-Dark.png\",\"width\":\"150\",\"height\":\"150\",\"caption\":\"WormholeRiders News Agency\"},\"image\":{\"@id\":\"https:\\\/\\\/www.wormholeriders.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jessica McLeod Archives - WormholeRiders News Agency","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.wormholeriders.com\/blog\/category\/celebs\/jessica-mcleod\/","og_locale":"en_US","og_type":"article","og_title":"Jessica McLeod Archives - WormholeRiders News Agency","og_url":"https:\/\/www.wormholeriders.com\/blog\/category\/celebs\/jessica-mcleod\/","og_site_name":"WormholeRiders News Agency","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.wormholeriders.com\/blog\/category\/celebs\/jessica-mcleod\/","url":"https:\/\/www.wormholeriders.com\/blog\/category\/celebs\/jessica-mcleod\/","name":"Jessica McLeod Archives - WormholeRiders News Agency","isPartOf":{"@id":"https:\/\/www.wormholeriders.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.wormholeriders.com\/blog\/category\/celebs\/jessica-mcleod\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.wormholeriders.com\/blog\/category\/celebs\/jessica-mcleod\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.wormholeriders.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Celebs","item":"https:\/\/www.wormholeriders.com\/blog\/category\/celebs\/"},{"@type":"ListItem","position":3,"name":"Jessica McLeod"}]},{"@type":"WebSite","@id":"https:\/\/www.wormholeriders.com\/blog\/#website","url":"https:\/\/www.wormholeriders.com\/blog\/","name":"WormholeRiders News Agency","description":"Please Keep Your Arms and Legs Inside the Wormhole at All Times!","publisher":{"@id":"https:\/\/www.wormholeriders.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.wormholeriders.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.wormholeriders.com\/blog\/#organization","name":"WormholeRiders News Agency","url":"https:\/\/www.wormholeriders.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.wormholeriders.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.wormholeriders.com\/blog\/wp-content\/uploads\/WormholeRiders-New-Logo-150TS-Dark.png","contentUrl":"https:\/\/www.wormholeriders.com\/blog\/wp-content\/uploads\/WormholeRiders-New-Logo-150TS-Dark.png","width":"150","height":"150","caption":"WormholeRiders News Agency"},"image":{"@id":"https:\/\/www.wormholeriders.com\/blog\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.wormholeriders.com\/blog\/wp-json\/wp\/v2\/categories\/9233","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.wormholeriders.com\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.wormholeriders.com\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/www.wormholeriders.com\/blog\/wp-json\/wp\/v2\/categories\/10"}],"wp:post_type":[{"href":"https:\/\/www.wormholeriders.com\/blog\/wp-json\/wp\/v2\/posts?categories=9233"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}